{"id":19,"date":"2017-07-19T14:53:35","date_gmt":"2017-07-19T14:53:35","guid":{"rendered":"http:\/\/wp.lancs.ac.uk\/fofi2018\/?page_id=19"},"modified":"2018-03-22T13:36:39","modified_gmt":"2018-03-22T13:36:39","slug":"call-for-papers","status":"publish","type":"page","link":"http:\/\/wp.lancs.ac.uk\/fofi2018\/call-for-papers\/","title":{"rendered":"Call for Papers"},"content":{"rendered":"<p><strong>Keynote Speakers<\/strong><\/p>\n<ul>\n<li>Marie Bri\u00e8re, Amundi Asset Management &amp; Paris Dauphine University<\/li>\n<li>Michael Fraikin, Invesco Quantitative Strategies<\/li>\n<li>Daniel Giamouridis, Bank of America Merrill Lynch<\/li>\n<li>Raman Uppal, EDHEC Business School and CEPR<\/li>\n<\/ul>\n<p>The <a href=\"http:\/\/www.lancaster.ac.uk\/lums\/research\/research-centres\/financial-econometrics\/\">Centre for Financial Econometrics, Asset Markets and Macroeconomic Policy (EMP)<\/a> at Lancaster University Management School and Invesco Quantitative Strategies invite the submission of papers in the field of factor investing and related research areas including:<\/p>\n<ul>\n<li>Asset pricing<\/li>\n<li>Investments<\/li>\n<li>Factor selection, optimisation and timing<\/li>\n<li>Global portfolio selection<\/li>\n<li>Risk management<\/li>\n<li>Factor Allocation<\/li>\n<li>Pricing Factors<\/li>\n<li>Return predictability<\/li>\n<li>Financial econometrics<\/li>\n<li>High-frequency finance<\/li>\n<li>Volatility modelling<\/li>\n<li>News sentiment<\/li>\n<li>Big data and machine learning<\/li>\n<li>Forecasting<\/li>\n<li>Model selection<\/li>\n<li>Extreme event modelling<\/li>\n<\/ul>\n<p>The best paper will be awarded the Invesco IQS Factor Investing Prize (GBP 2000).<\/p>\n<p><strong>Closing data for paper submission: January 15, 2018<\/strong><\/p>\n<p>Papers should be submitted in electronic format (pdf) via email to <a href=\"mailto:emp@lancaster.ac.uk\">emp@lancaster.ac.uk<\/a>. Please include your contact information and affiliation.<\/p>\n<p>Download our <a href=\"http:\/\/wp.lancs.ac.uk\/fofi2018\/files\/2017\/07\/Call-For-Papers-Lancaster-2018.pdf\">Call For Papers<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keynote Speakers Marie Bri\u00e8re, Amundi Asset Management &amp; Paris Dauphine University Michael Fraikin, Invesco Quantitative Strategies Daniel Giamouridis, Bank of America Merrill Lynch Raman Uppal, EDHEC Business School and CEPR The Centre for Financial Econometrics, Asset Markets and Macroeconomic Policy &hellip; <a href=\"http:\/\/wp.lancs.ac.uk\/fofi2018\/call-for-papers\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":607,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/users\/607"}],"replies":[{"embeddable":true,"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":9,"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":140,"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/pages\/19\/revisions\/140"}],"wp:attachment":[{"href":"http:\/\/wp.lancs.ac.uk\/fofi2018\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}