{"id":81,"count":1,"description":"","link":"http:\/\/wp.lancs.ac.uk\/decolonising\/tag\/scholarship\/","name":"Scholarship","slug":"scholarship","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/wp.lancs.ac.uk\/decolonising\/wp-json\/wp\/v2\/tags\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wp.lancs.ac.uk\/decolonising\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/wp.lancs.ac.uk\/decolonising\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/wp.lancs.ac.uk\/decolonising\/wp-json\/wp\/v2\/posts?tags=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}